{"id":352,"date":"2025-03-23T00:59:22","date_gmt":"2025-03-22T23:59:22","guid":{"rendered":"http:\/\/www.derechopenaladministrativo.es\/?p=352"},"modified":"2025-03-23T01:23:49","modified_gmt":"2025-03-23T00:23:49","slug":"cometen-delito-los-periodistas-al-publicar-secretos-de-sumario","status":"publish","type":"post","link":"https:\/\/www.sorianoipiqueras.com\/derechopenaladministrativo\/cometen-delito-los-periodistas-al-publicar-secretos-de-sumario\/","title":{"rendered":"\u00bfCometen delito los periodistas al publicar filtraciones de una causa penal?"},"content":{"rendered":"\n<p>Un asunto de la m\u00e1xima actualidad jur\u00eddica y medi\u00e1tica ha surgido a ra\u00edz de la investigaci\u00f3n penal al fiscal general&nbsp;<strong>\u00c1lvaro Garc\u00eda Ortiz<\/strong>: varios periodistas han sido citados como investigados por difundir el contenido de un informe de la UCO que formaba parte de dicha investigaci\u00f3n. Esta situaci\u00f3n in\u00e9dita ha reabierto el debate sobre el&nbsp;<strong>car\u00e1cter reservado de la instrucci\u00f3n penal<\/strong>&nbsp;y las consecuencias jur\u00eddicas de revelar a la prensa informaci\u00f3n de un procedimiento penal en curso. Pero, <strong>\u00bfpuede responder penalmente un periodista por publicar informaci\u00f3n de unas actuaciones judiciales?<\/strong><\/p>\n\n\n\n<p>Hemos de partir de un hecho muchas veces pasado por alto incluso por profesionales del derecho:&nbsp;<strong>toda instrucci\u00f3n penal es reservada para los que no son parte<\/strong>, aunque no se haya declarado formalmente el llamado \u201csecreto de sumario\u201d. As\u00ed lo establece el art\u00edculo 301 de la Ley de Enjuiciamiento Criminal (LECrim), cuyo p\u00e1rrafo primero se\u00f1ala que&nbsp;<em>las diligencias del sumario ser\u00e1n reservadas y no tendr\u00e1n car\u00e1cter p\u00fablico hasta que se abra el juicio oral<\/em>, salvo contadas excepciones.<\/p>\n\n\n\n<p>Este deber de reserva -al que la redacci\u00f3n original de la LECrim de 1882 se refer\u00eda como <em>secreto<\/em>&#8211; busca proteger la eficacia de la investigaci\u00f3n y derechos como la intimidad o la presunci\u00f3n de inocencia de los implicados. Ahora bien, ello no significa que&nbsp;<strong>todo lo actuado en la fase de instrucci\u00f3n sea secreto absoluto<\/strong>: la jurisprudencia del Tribunal Supremo (por ejemplo, la&nbsp;<strong>STS 1020\/1995, de 19 de octubre<\/strong>) ha matizado que \u00fanicamente quedan vedados por la reserva aquellos extremos que podr\u00edan&nbsp;<strong>perjudicar el \u00e9xito de la investigaci\u00f3n<\/strong>&nbsp;o&nbsp;<strong>afectar derechos fundamentales<\/strong>&nbsp;(declaraciones de imputados o testigos, informes periciales o policiales, etc.), pero no las resoluciones judiciales de tr\u00e1mite ni otros elementos menos sensibles del proceso.<\/p>\n\n\n\n<p>Sentado lo anterior, la cuesti\u00f3n central es qu\u00e9 consecuencias tiene&nbsp;<strong>vulnerar ese deber de reserva<\/strong>&nbsp;difundiendo p\u00fablicamente informaci\u00f3n sumarial. El propio art\u00edculo 301 LECrim, en sus p\u00e1rrafos siguientes, establece una&nbsp;<strong>distinci\u00f3n muy clara seg\u00fan qui\u00e9n sea el autor de la filtraci\u00f3n<\/strong>: si la revela un particular (por ejemplo, un abogado, procurador o incluso una de las partes personadas) la conducta se considera una&nbsp;<em>infracci\u00f3n procesal<\/em>&nbsp;sancionable por el juez instructor&nbsp;con una multa. En la misma multa incurrir\u00e1, dice la ley,&nbsp;<em>\u201ccualquier otra persona\u201d<\/em>&nbsp;que,&nbsp;<strong>no siendo funcionario p\u00fablico<\/strong>, cometa la misma falta.<\/p>\n\n\n\n<p>Por el contrario, si quien divulga indebidamente el contenido reservado es un <strong>funcionario o autoridad<\/strong>\u00a0que lo conoce por raz\u00f3n de su cargo (pi\u00e9nsese en un juez, fiscal, secretario judicial o polic\u00eda, o incluso un abogado del Estado), entonces\u00a0<strong>entra en juego el C\u00f3digo Penal<\/strong>: el art\u00edculo 417 CP tipifica la\u00a0revelaci\u00f3n de secretos\u00a0por funcionario, castig\u00e1ndola incluso con penas de <strong>prisi\u00f3n de hasta 3 a\u00f1os<\/strong>\u00a0e inhabilitaci\u00f3n, especialmente si de la filtraci\u00f3n resulta un grave da\u00f1o para la causa o para terceros. En resumen, nuestro sistema jur\u00eddico\u00a0<strong>solo configura como delito<\/strong>\u00a0la revelaci\u00f3n de actuaciones sumariales\u00a0<strong>cuando la comete una autoridad o funcionario<\/strong>\u00a0obligado legalmente a guardar secreto. Para los dem\u00e1s casos (abogados, partes, periodistas u otros ciudadanos), la consecuencia prevista es\u00a0<strong>una sanci\u00f3n disciplinaria o multa<\/strong>, no una pena criminal.<\/p>\n\n\n\n<p>Esta diferenciaci\u00f3n legislativa tiene pleno sentido. El funcionario p\u00fablico involucrado en la investigaci\u00f3n tiene un&nbsp;<strong>deber jur\u00eddico espec\u00edfico de sigilo<\/strong>&nbsp;cuya violaci\u00f3n se considera especialmente reprochable, de ah\u00ed la intervenci\u00f3n del Derecho Penal. En cambio, quienes no ostentan esa posici\u00f3n (entre ellos los periodistas) no tienen,&nbsp;<em>stricto sensu<\/em>, ese deber legal directo, m\u00e1s all\u00e1 de la gen\u00e9rica obligaci\u00f3n de respetar las leyes. Por ello, la&nbsp;<strong>mera difusi\u00f3n period\u00edstica<\/strong>&nbsp;de materiales de un sumario no quebranta ning\u00fan deber jur\u00eddico personal equiparable al de un funcionario. De hecho, en la pr\u00e1ctica judicial espa\u00f1ola ha sido habitual que ciertos detalles de casos relevantes lleguen a la prensa sin que se persiga penalmente a los periodistas que los publican. Lo usual, en todo caso, ser\u00eda que el juez instructor reaccionara apercibiendo a las partes o imponiendo alguna multa simb\u00f3lica a quien identificara como filtrador, pero&nbsp;<strong>raramente se traslada el asunto a la jurisdicci\u00f3n penal<\/strong>&nbsp;trat\u00e1ndose de personas ajenas a la funci\u00f3n p\u00fablica.<\/p>\n\n\n\n<p>\u00bfSignifica esto que nunca podr\u00eda imputarse un delito a un periodista por publicar filtraciones? Hay pocos precedentes jurisprudenciales de situaciones an\u00e1logas, pero han servido para sentar una doctrina al respecto: los casos Raquel Rend\u00f3n y Cursach.<\/p>\n\n\n\n<p>En el denominado caso Raquel Rend\u00f3n, la periodista fue acusada del delito de descubrimiento y revelaci\u00f3n de secretos, del art\u00edculo 197 del C\u00f3digo Penal por difundir informaci\u00f3n de una causa penal, siendo condenada por la Audiencia Provincial de Huelva. La Sala de lo Civil y lo Penal del Tribunal Superior de Justicia de Andaluc\u00eda la absolvi\u00f3 en sentencia dictada en el verano de 2024, sentando tres criterios para la imputaci\u00f3n delictiva al periodista por difundir la informaci\u00f3n del sumario: <\/p>\n\n\n\n<p>(1)&nbsp;<strong>Existencia de prueba plena del car\u00e1cter il\u00edcito de la filtraci\u00f3n<\/strong>&nbsp;y del conocimiento delictivo por parte del periodista, no bastando la mera sospecha\u200b,<\/p>\n\n\n\n<p>(2) Que el informador haya contribuido activamente a vulnerar el deber legal de reserva.<\/p>\n\n\n\n<p>(3) Debe prevalecer la libertad de informaci\u00f3n sobre el secreto, salvo que este \u00faltimo proteja valores superiores de forma concreta (por ejemplo, evitar un da\u00f1o grav\u00edsimo e irreparable).&nbsp;<\/p>\n\n\n\n<p>Por su parte, en el denominado caso Cursach, el Tribunal Superior de Justicia de las Illes Balears declar\u00f3 nulos los rastreos y la incautaci\u00f3n de tel\u00e9fonos de periodistas de Europa Press y Diario de Mallorca para averiguar hechos delictivos derivados de la filtraci\u00f3n de informaci\u00f3n sumarial, al considerar que la informaci\u00f3n contenida en sus terminales telef\u00f3nicos estaba amparada por el secreto profesional -el derecho a la confidencialidad de las fuentes-, cuya vulneraci\u00f3n supondr\u00eda un ataque a la libertad de informaci\u00f3n. <\/p>\n\n\n\n<p>Otra v\u00eda para intentar atribuir responsabilidad penal al periodista ser\u00eda forzar su encaje como&nbsp;<strong>part\u00edcipe<\/strong>&nbsp;en el delito del funcionario filtrador (por ejemplo, como inductor o cooperador necesario de la revelaci\u00f3n de secretos del art\u00edculo 417 CP). Sin embargo, la mera recepci\u00f3n de informaci\u00f3n y su difusi\u00f3n en una noticia dif\u00edcilmente encaja en estas figuras de participaci\u00f3n criminal, salvo que se demostrase una&nbsp;<strong>concertaci\u00f3n previa<\/strong>&nbsp;o alg\u00fan ofrecimiento concreto del periodista que provocase al funcionario a violar el secreto. Dicho de otro modo, si el periodista se limita a ejercer su labor informativa difundiendo datos obtenidos de una fuente, no est\u00e1 coadyuvando deliberadamente a un delito, sino cumpliendo con su funci\u00f3n de informar. <\/p>\n\n\n\n<p>Al contrario, frente a cualquier intento de criminalizar al mensajero, surge con fuerza la protecci\u00f3n del&nbsp;<strong>derecho fundamental a la informaci\u00f3n<\/strong>&nbsp;recogido en el art\u00edculo 20 de la Constituci\u00f3n. Este derecho ampara las publicaciones de relevancia p\u00fablica incluso cuando incomodan al poder o afectan a procedimientos en curso, siempre que se trate de informaciones veraces y de inter\u00e9s general. Nuestro Tribunal Constitucional tradicionalmente ha sido garante de la libertad de prensa en contextos similares, sosteniendo que las restricciones al flujo informativo deben ser&nbsp;<strong>muy excepcionales<\/strong>&nbsp;y estar justificadas por bienes superiores en juego.<\/p>\n\n\n\n<p>En el caso de las filtraciones de sumarios, es evidente que existe un conflicto entre ese inter\u00e9s informativo (que en asuntos de corrupci\u00f3n pol\u00edtica o causas de alto inter\u00e9s p\u00fablico resulta incuestionable) y la necesidad de preservar el buen fin de la investigaci\u00f3n, pero la soluci\u00f3n a ese conflicto dif\u00edcilmente puede pasar por&nbsp;<strong>penalizar al periodista<\/strong>&nbsp;que divulga la informaci\u00f3n. M\u00e1s bien deber\u00eda centrarse en perseguir al origen de la filtraci\u00f3n il\u00edcita \u2014es decir, al funcionario o sujeto obligado que viol\u00f3 su deber\u2014 o en adoptar medidas de protecci\u00f3n del sumario menos lesivas para la libertad informativa (por ejemplo, limitar el acceso a ciertos documentos sensibles, como ha hecho recientemente el magistrado del&nbsp;<em>caso Garc\u00eda Ortiz<\/em>&nbsp;al retener temporalmente las grabaciones de declaraciones para evitar nuevas filtraciones).<\/p>\n\n\n\n<p>En definitiva, la&nbsp;<strong>responsabilidad penal por publicar informaci\u00f3n de un sumario reservado es pr\u00e1cticamente inexistente para los periodistas<\/strong>&nbsp;bajo el derecho espa\u00f1ol. Las actuaciones de los jueces frente a filtraciones deben ce\u00f1irse a sancionar o investigar a quien ten\u00eda el deber legal de guardar la reserva (y eventualmente a reforzar las cautelas en el procedimiento), pero tratar de castigar al medio de comunicaci\u00f3n que difunde la noticia supondr\u00eda adentrarse en terrenos muy resbaladizos para la libertad de informaci\u00f3n. Es previsible, adem\u00e1s, que cualquier intento de criminalizar a periodistas por estas divulgaciones terminar\u00eda siendo objeto de un intenso escrutinio por parte del&nbsp;<strong>Tribunal Europeo de Derechos Humanos<\/strong>, llamado a equilibrar la protecci\u00f3n del secreto de las investigaciones con el valor esencial de una prensa libre en una sociedad democr\u00e1tica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un asunto de la m\u00e1xima actualidad jur\u00eddica y medi\u00e1tica ha surgido a ra\u00edz de la investigaci\u00f3n penal al fiscal general&nbsp;\u00c1lvaro Garc\u00eda Ortiz: varios periodistas han sido citados como investigados por difundir el contenido de un informe de la UCO que formaba parte de dicha investigaci\u00f3n. Esta situaci\u00f3n in\u00e9dita ha reabierto el debate sobre el&nbsp;car\u00e1cter reservado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":354,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-352","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.sorianoipiqueras.com\/derechopenaladministrativo\/wp-json\/wp\/v2\/posts\/352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sorianoipiqueras.com\/derechopenaladministrativo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sorianoipiqueras.com\/derechopenaladministrativo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sorianoipiqueras.com\/derechopenaladministrativo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sorianoipiqueras.com\/derechopenaladministrativo\/wp-json\/wp\/v2\/comments?post=352"}],"version-history":[{"count":5,"href":"https:\/\/www.sorianoipiqueras.com\/derechopenaladministrativo\/wp-json\/wp\/v2\/posts\/352\/revisions"}],"predecessor-version":[{"id":358,"href":"https:\/\/www.sorianoipiqueras.com\/derechopenaladministrativo\/wp-json\/wp\/v2\/posts\/352\/revisions\/358"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sorianoipiqueras.com\/derechopenaladministrativo\/wp-json\/wp\/v2\/media\/354"}],"wp:attachment":[{"href":"https:\/\/www.sorianoipiqueras.com\/derechopenaladministrativo\/wp-json\/wp\/v2\/media?parent=352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sorianoipiqueras.com\/derechopenaladministrativo\/wp-json\/wp\/v2\/categories?post=352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sorianoipiqueras.com\/derechopenaladministrativo\/wp-json\/wp\/v2\/tags?post=352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}